{"id":468,"date":"2018-11-27T09:16:54","date_gmt":"2018-11-27T09:16:54","guid":{"rendered":"https:\/\/kazbeehoney.com\/index.php\/home\/"},"modified":"2025-01-03T21:28:58","modified_gmt":"2025-01-03T21:28:58","slug":"home","status":"publish","type":"page","link":"https:\/\/kazbeehoney.com\/nl\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"468\" class=\"elementor elementor-468\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c50838b elementor-section-height-min-height elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"c50838b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f84d6d\" data-id=\"2f84d6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-55b0429\" data-id=\"55b0429\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecae13e elementor-widget elementor-widget-image\" data-id=\"ecae13e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"484\" height=\"484\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2025\/01\/bee-favicon-square.png\" class=\"attachment-full size-full wp-image-1542\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2025\/01\/bee-favicon-square.png 484w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2025\/01\/bee-favicon-square-300x300.png 300w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2025\/01\/bee-favicon-square-150x150.png 150w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2025\/01\/bee-favicon-square-12x12.png 12w\" sizes=\"(max-width: 484px) 100vw, 484px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea32801 elementor-widget elementor-widget-heading\" data-id=\"ea32801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Welcome to KazBee Honey<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92570e2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"92570e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-453e782 elementor-widget elementor-widget-heading\" data-id=\"453e782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pure Honey Straight from the Heart of Nature\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04c08ab elementor-widget elementor-widget-text-editor\" data-id=\"04c08ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At KazBee Honey, we take pride in crafting 100% natural honey from our family-run beekeeping farm. Explore our diverse range of honey varieties, harvested with love and care, to bring the purest, healthiest flavors to your table.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-79b148e\" data-id=\"79b148e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a69f681 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a69f681\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16825f4\" data-id=\"16825f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e7443 elementor-widget elementor-widget-heading\" data-id=\"e5e7443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Honey Varieties<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66852a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66852a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0304c3f\" data-id=\"0304c3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56e7952\" data-id=\"56e7952\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ccb8bb elementor-widget elementor-widget-text-editor\" data-id=\"5ccb8bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We offer a wide selection of honey types, each with its own unique flavor and health benefits<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-151b4b0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"151b4b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-775de24\" data-id=\"775de24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46a2d50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46a2d50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c0e0e43\" data-id=\"c0e0e43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e59a0cd elementor-widget elementor-widget-image\" data-id=\"e59a0cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"992\" height=\"1025\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Acacia-honing-coming-soon.png\" class=\"attachment-full size-full wp-image-1021\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Acacia-honing-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Acacia-honing-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Acacia-honing-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Acacia-honing-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-543ac2e elementor-widget elementor-widget-image-box\" data-id=\"543ac2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Acacia Honey<\/h5><p class=\"elementor-image-box-description\">Delicate, mild flavor with floral notes, made from the nectar of acacia tree blossoms. One of the lightest and most liquid honey types.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8de150b elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"8de150b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/acacia-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c614c4\" data-id=\"2c614c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7da6c6c elementor-widget elementor-widget-image\" data-id=\"7da6c6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1022\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba141ea elementor-widget elementor-widget-image-box\" data-id=\"ba141ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Buckweat Honey<\/h5><p class=\"elementor-image-box-description\">Dark and rich in flavor, known for its strong taste and high antioxidant content. Perfect for those who prefer bold, earthy notes in their honey<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30030a0 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"30030a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/buckwheat-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c518ec\" data-id=\"2c518ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ed3240 elementor-widget elementor-widget-image\" data-id=\"7ed3240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1023\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4021082 elementor-widget elementor-widget-image-box\" data-id=\"4021082\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Heather Honey<\/h5><p class=\"elementor-image-box-description\">This honey boasts a strong, slightly bitter taste with an intense, aromatic fragrance. Known for its high mineral content, it pairs wonderfully with cheese.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c3d13 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"29c3d13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/heather-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5415cda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5415cda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4443b31\" data-id=\"4443b31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cddbdca elementor-widget elementor-widget-image\" data-id=\"cddbdca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1024\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbba76 elementor-widget elementor-widget-image-box\" data-id=\"3fbba76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Melilot Honey<\/h5><p class=\"elementor-image-box-description\">A light, fragrant honey with hints of vanilla and herbal notes. Often used for soothing purposes and perfect in warm drinks.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66a5ddb elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"66a5ddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/melilot-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-be7a606\" data-id=\"be7a606\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37869cf elementor-widget elementor-widget-image\" data-id=\"37869cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now.png\" class=\"attachment-full size-full wp-image-1025\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e52b68d elementor-widget elementor-widget-image-box\" data-id=\"e52b68d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Rapeseed Honey<\/h5><p class=\"elementor-image-box-description\">Creamy and smooth, with a sweet and mildly floral taste. Often used in cooking or as a spread due to its easily spreadable texture.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f31873 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4f31873\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/rapeseed-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-da141dc\" data-id=\"da141dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad058e6 elementor-widget elementor-widget-image\" data-id=\"ad058e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1026\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-033f20e elementor-widget elementor-widget-image-box\" data-id=\"033f20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Linden Honey<\/h5><p class=\"elementor-image-box-description\">Harvested from linden trees, this honey has a minty, herbal aftertaste and is commonly used to soothe colds and promote relaxation.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c50189e elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"c50189e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/linden-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50e8c28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50e8c28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bb98d5f\" data-id=\"bb98d5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9619b64 elementor-widget elementor-widget-image\" data-id=\"9619b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1027\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb8114 elementor-widget elementor-widget-image-box\" data-id=\"8bb8114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Milk Thistle Honey<\/h5><p class=\"elementor-image-box-description\">A delicate, mild honey with a subtle floral taste, known for supporting liver health. Ideal for tea or as a natural sweetener.\n\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97cfd0d elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"97cfd0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/milk-thistle-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c36536e\" data-id=\"c36536e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-796aa7d elementor-widget elementor-widget-image\" data-id=\"796aa7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1028\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f251689 elementor-widget elementor-widget-image-box\" data-id=\"f251689\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Phacelia Honey<\/h5><p class=\"elementor-image-box-description\">Light and clear with a mild, sweet flavor. Phacelia honey is prized for its delicate floral notes, perfect for those who enjoy a lighter sweetness.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9919d1d elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9919d1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/phacelia-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8b9cd3b\" data-id=\"8b9cd3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b86a98 elementor-widget elementor-widget-image\" data-id=\"1b86a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1026\" src=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon.png\" class=\"attachment-full size-full wp-image-1029\" alt=\"\" srcset=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon.png 992w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon-290x300.png 290w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon-990x1024.png 990w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon-768x794.png 768w, https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon-12x12.png 12w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff2fa2d elementor-widget elementor-widget-image-box\" data-id=\"ff2fa2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Wildflower Honey<\/h5><p class=\"elementor-image-box-description\">A beautiful blend of various wildflower nectars, offering a rich, complex flavor with every spoonful. Great for everyday use.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-636937f elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"636937f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kazbeehoney.com\/nl\/products\/wildflower-honey\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Read more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51af88c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51af88c\" data-element_type=\"section\" data-e-type=\"section\" id=\"readmore\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0bec06\" data-id=\"b0bec06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a9a69dd\" data-id=\"a9a69dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd80664 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd80664\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f8a482\" data-id=\"1f8a482\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11b62bd elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"11b62bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;5&quot;,&quot;autoplay_speed&quot;:10000,&quot;lazyload&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper-container\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/rapeseed-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"koolzaadhoning - pasiekaukazia - Available now\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/koolzaadhoning-pasiekaukazia-Available-now.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/phacelia-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"phaceliahoning - pasiekaukazia coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/phaceliahoning-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/linden-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Lindehoning - pasiekaukazia - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Lindehoning-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/heather-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Heidehoning - pasiekaukazia - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Heidehoning-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/melilot-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Honingklaver honing - pasiekaukazia - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Honingklaver-honing-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/wildflower-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Wilde bloemen honing - pasiekaukazia - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Wilde-bloemen-honing-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/milk-thistle-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Mariadistel honing - pasiekaukazia - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Mariadistel-honing-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/buckwheat-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Boekweithoning - pasiekaukazia - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Boekweithoning-pasiekaukazia-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/kazbeehoney.com\/nl\/products\/acacia-honey\/\">\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Acacia honing - coming soon\" data-background=\"https:\/\/kazbeehoney.com\/wp-content\/uploads\/2024\/11\/Acacia-honing-coming-soon.png\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d59e0c7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d59e0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Welcome to KazBee Honey Pure Honey Straight from the Heart of Nature At KazBee Honey, we take pride in crafting 100% natural honey from our family-run beekeeping farm. Explore our diverse range of honey varieties, harvested with love and care, to bring the purest, healthiest flavors to your table. Our Honey Varieties We offer a [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-468","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/pages\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/comments?post=468"}],"version-history":[{"count":124,"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/pages\/468\/revisions"}],"predecessor-version":[{"id":1718,"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/pages\/468\/revisions\/1718"}],"wp:attachment":[{"href":"https:\/\/kazbeehoney.com\/nl\/wp-json\/wp\/v2\/media?parent=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}